{"id":1350,"date":"2023-10-11T10:48:00","date_gmt":"2023-10-11T08:48:00","guid":{"rendered":"https:\/\/www.calvert.ch\/maurice\/?p=1350"},"modified":"2025-09-28T14:23:15","modified_gmt":"2025-09-28T12:23:15","slug":"maitrise-des-couts-de-la-sante","status":"publish","type":"post","link":"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/maitrise-des-couts-de-la-sante\/","title":{"rendered":"Ma\u00eetrise des co\u00fbts de la sant\u00e9 : Une solution par la transparence"},"content":{"rendered":"\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<p class=\"has-small-font-size wp-container-content-9cfa9a5a wp-block-paragraph\"><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/beherrschung-der-gesundheitskosten-eine-losung-durch-transparenz\/\">Auf Deutsch<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-container-content-9cfa9a5a wp-block-paragraph\"><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/controllo-dei-costi-sanitari-una-soluzione-attraverso-la-trasparenza\/\">In italiano<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-container-content-9cfa9a5a wp-block-paragraph\"><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/gsundheitschoschte-im-griff-ha-e-losig-dur-transparanz\/\"><\/a><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/controll-dals-custs-da-la-sanadad-ina-soluziun-tras-transparenza\/\">En rumantsch<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-container-content-9cfa9a5a wp-block-paragraph\"><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/gsundheitschoschte-im-griff-ha-e-losig-dur-transparanz\/\">Uf Schwiizerd\u00fctsch<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-container-content-9cfa9a5a wp-block-paragraph\"><a href=\"https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/controlling-healthcare-costs-a-solution-through-transparency\/\">In English<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les id\u00e9es pour baisser les co\u00fbts sont nombreuses, mais il est impossible d\u2019\u00e9valuer leur efficacit\u00e9 car nous ne savons pas exactement o\u00f9 et comment l\u2019argent est d\u00e9pens\u00e9.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Proposition<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">La Conf\u00e9d\u00e9ration mandate l\u2019Office F\u00e9d\u00e9ral de la Statistique pour r\u00e9aliser une \u00e9tude annuelle des finances de la sant\u00e9. Pour ce faire, tous les assureurs fourniront \u00e0 l\u2019OFS les donn\u00e9es d\u00e9taill\u00e9es permettant de chiffrer individuellement chaque prestation&nbsp;: acte, m\u00e9dicament, prime, franchise, remboursement, quote-part, etc. Une analyse avec une granularit\u00e9 aussi fine permettra une compr\u00e9hension des finances de la sant\u00e9 qui \u00e9tait impossible jusqu\u2019alors.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Avantages<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Il serait possible de chiffrer rigoureusement les \u00e9conomies r\u00e9alisables pour chaque mesure propos\u00e9e. Ceci permettra de&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Piloter la politique de la sant\u00e9 avec pr\u00e9cision, sans inconnues.<\/li>\n\n\n\n<li>Abr\u00e9ger les d\u00e9bats, actuellement bas\u00e9s sur des suppositions d\u2019\u00e9conomies.<\/li>\n\n\n\n<li>Prendre des d\u00e9cisions rapidement, en sachant exactement les cons\u00e9quences.<\/li>\n\n\n\n<li>Choisir les mesures qui g\u00e9n\u00e9reront les plus grandes r\u00e9ductions des co\u00fbts.<\/li>\n\n\n\n<li>Ecarter les discussions autour de mesures clairement insignifiantes.<\/li>\n\n\n\n<li>Identifier les distortions dans les prix.<\/li>\n\n\n\n<li>D\u00e9tecter les abus.<\/li>\n\n\n\n<li>Faire des d\u00e9couvertes inattendues, par exemple&nbsp;: Autour du Lac des Quatre Cantons, le m\u00e9dicament X est prescrit 3 fois plus que la moyenne, pourquoi&nbsp;?<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Objections pr\u00e9visibles<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Cela co\u00fbtera cher<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les co\u00fbts de la sant\u00e9 en Suisse en 2021 \u00e9taient de <a href=\"https:\/\/www.bfs.admin.ch\/bfs\/fr\/home\/statistiques\/sante\/cout-financement.html\">CHF 827<\/a> par habitant et par mois, soit CHF&nbsp;86&#8217;344&#8217;000&#8217;000. M\u00eame si l\u2019\u00e9tude initiale co\u00fbte quelques millions, c\u2019est insignifiant en regard des \u00e9conomies potentielles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Violation du secret m\u00e9dical<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019OFS sp\u00e9cifiera comment les donn\u00e9es seront agr\u00e9g\u00e9es, vraisemblablement par localit\u00e9, \u00e2ge et sexe du patient. Il serait ainsi impossible d\u2019identifier un individu.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ces donn\u00e9es appartiennent aux assureurs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Une donn\u00e9e est g\u00e9n\u00e9r\u00e9e quand une personne subit un traitement&nbsp;ou paie une prestation ; cette donn\u00e9e appartient \u00e0 celui qui la cr\u00e9e. Individuellement elle lui est personnelle, agr\u00e9g\u00e9es elles appartiennent \u00e0 la collectivit\u00e9. Les assureurs h\u00e9bergent ces donn\u00e9es, ils n\u2019en sont pas les propri\u00e9taires. Par ailleurs, ces donn\u00e9es existent d\u00e9j\u00e0 chez les m\u00e9decins, les pharmaciens et les h\u00f4pitaux&nbsp;; c\u2019est simplement plus efficace de les r\u00e9colter aupr\u00e8s des assureurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Divulguer ces donn\u00e9es serait d\u00e9loyal pour les assureurs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si tous les assureurs doivent participer, aucun ne serait (d\u00e9s)avantag\u00e9. S\u2019ils n\u2019ont rien \u00e0 cacher, ils n\u2019ont rien \u00e0 craindre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La quantit\u00e9 de donn\u00e9es serait ing\u00e9rable<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Supposons que tous les habitants sont en traitement permanent et qu\u2019il faille une page A4 pour d\u00e9crire le traitement de chacun, chaque mois. 9&#8217;000&#8217;000 d\u2019habitants \u00d7 12 mois \u00d7 3&#8217;000 octets = 324&nbsp;GigaOctets. Une clef USB de 512 GigaOctets co\u00fbte CHF 31.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf Deutsch In italiano En rumantsch Uf Schwiizerd\u00fctsch In English Les id\u00e9es pour baisser les co\u00fbts sont nombreuses, mais il est impossible d\u2019\u00e9valuer leur efficacit\u00e9 car nous ne savons pas exactement o\u00f9 et comment l\u2019argent est d\u00e9pens\u00e9. Proposition La Conf\u00e9d\u00e9ration <a href='https:\/\/www.calvert.ch\/maurice\/2023\/10\/11\/maitrise-des-couts-de-la-sante\/' class='excerpt-more'>[&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,68],"tags":[],"class_list":["post-1350","post","type-post","status-publish","format-standard","hentry","category-politics","category-sante","category-8-id","category-68-id","post-seq-1","post-parity-odd","meta-position-corners","fix"],"_links":{"self":[{"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/posts\/1350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/comments?post=1350"}],"version-history":[{"count":7,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/posts\/1350\/revisions"}],"predecessor-version":[{"id":1382,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/posts\/1350\/revisions\/1382"}],"wp:attachment":[{"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/media?parent=1350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/categories?post=1350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.calvert.ch\/maurice\/wp-json\/wp\/v2\/tags?post=1350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}